{"id":3522,"date":"2023-09-21T12:20:04","date_gmt":"2023-09-21T15:20:04","guid":{"rendered":"https:\/\/buzios-vibe.com\/joao-fernandes-il-quartiere-degli-sport-acquatici-di-buzios"},"modified":"2024-11-15T15:32:31","modified_gmt":"2024-11-15T18:32:31","slug":"joao-fernandes-il-quartiere-degli-sport-acquatici-di-buzios","status":"publish","type":"post","link":"https:\/\/buzios-vibe.com\/it\/joao-fernandes-il-quartiere-degli-sport-acquatici-di-buzios","title":{"rendered":"Jo\u00e3o Fernandes: il quartiere degli sport acquatici di B\u00fazios"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Situato sulla costa nord-orientale della penisola di B\u00fazios, Jo\u00e3o Fernandes \u00e8 un quartiere rinomato per le sue spiagge incontaminate, i suoi resort di lusso e un ambiente che racchiude perfettamente lo spirito di B\u00fazios. Questa zona, che prende il nome dalla sua spiaggia di punta, Praia Jo\u00e3o Fernandes, offre un mix di relax e avventura a ogni visitatore. Si trova tra il quartiere<a href=\"https:\/\/buzios-vibe.com\/it\/esplorare-ossos-a-buzios-un-quartiere-ricco-di-fascino\" target=\"_blank\" rel=\"noreferrer noopener\">&#8220;Ossos<\/a>&#8221; e<a href=\"https:\/\/buzios-vibe.com\/it\/brava-il-quartiere-selvaggio-e-bohemien-di-buzios\" target=\"_blank\" rel=\"noreferrer noopener\">&#8220;Brava<\/a>&#8220;.<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>Il fascino di Praia Jo\u00e3o Fernandes e Praia Jo\u00e3o Fernandinho<\/strong><\/h2>\n\n<h3 class=\"wp-block-heading\"><strong>Bellezza mozzafiato<\/strong><\/h3>\n\n<p class=\"wp-block-paragraph\">Sia Praia Jo\u00e3o Fernandes che la sua controparte pi\u00f9 piccola, Praia Jo\u00e3o Fernandinho, vantano sabbie dorate e acque cristalline. Circondate da affioramenti rocciosi e colline verdeggianti, queste spiagge offrono panorami da cartolina a ogni sguardo.<\/p>\n\n<h3 class=\"wp-block-heading\"><strong>Rifugio degli sport acquatici<\/strong><\/h3>\n\n<p class=\"wp-block-paragraph\">Le acque calme e trasparenti di queste spiagge sono ideali per lo snorkeling, consentendo agli appassionati di esplorare la vivace vita marina. Paddleboard, kayak e soprattutto <a href=\"https:\/\/buzios-vibe.com\/it\/immersioni-subacquee-a-buzios-esplorare-il-paese-delle-meraviglie-sottomarine-del-brasile\" target=\"_blank\" rel=\"noreferrer noopener\">immersioni subacquee<\/a> sono altre attivit\u00e0 molto popolari tra i turisti. A Jo\u00e3o Fernandes, in particolare, sono presenti diversi operatori di immersioni subacquee che offrono immersioni sia per i principianti che per i subacquei esperti, svelando le meraviglie sottomarine di B\u00fazios.<\/p>\n\n<h3 class=\"wp-block-heading\"><strong>Delizia gastronomica<\/strong><\/h3>\n\n<p class=\"wp-block-paragraph\">Il lungomare \u00e8 costellato di chioschi e ristoranti che offrono una variet\u00e0 di cucine. Dai frutti di mare freschi alle prelibatezze brasiliane, l&#8217;esperienza culinaria di Jo\u00e3o Fernandes \u00e8 davvero deliziosa.<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>Alloggi: Una miscela di lusso e comfort<\/strong><\/h2>\n\n<h3 class=\"wp-block-heading\"><strong>Hotel e resort di charme<\/strong><\/h3>\n\n<p class=\"wp-block-paragraph\">Jo\u00e3o Fernandes ospita alcuni dei resort e dei boutique hotel pi\u00f9 sfarzosi di B\u00fazios. Queste strutture non solo offrono viste mozzafiato sull&#8217;oceano, ma offrono anche servizi come servizi termali, piscine a sfioro e opzioni di ristorazione gourmet.<\/p>\n\n<h3 class=\"wp-block-heading\"><strong>Pousadas: Un&#8217;esperienza familiare<\/strong><\/h3>\n\n<p class=\"wp-block-paragraph\">Per i viaggiatori in cerca di un&#8217;esperienza pi\u00f9 intima, il quartiere vanta diverse &#8220;pousadas&#8221; o pensioni. Si tratta spesso di strutture a conduzione familiare, che offrono un soggiorno accogliente e personalizzato.<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>Oltre la spiaggia: Esplorando Jo\u00e3o Fernandes<\/strong><\/h2>\n\n<h3 class=\"wp-block-heading\"><strong>Mirante Jo\u00e3o Fernandes<\/strong><\/h3>\n\n<p class=\"wp-block-paragraph\">Questo punto di osservazione offre una vista elevata e senza ostacoli sulle spiagge e sulla costa circostante. \u00c8 un luogo perfetto per gli amanti del tramonto e della fotografia. \u00c8 un bel <a href=\"https:\/\/buzios-vibe.com\/it\/il-paradiso-dei-pedali-guida-alla-bicicletta-a-buzios-e-dintorni\" target=\"_blank\" rel=\"noreferrer noopener\">percorso da fare in bicicletta<\/a> o in <a href=\"https:\/\/buzios-vibe.com\/it\/tour-in-buggy-a-buzios-un-modo-unico-per-esplorare-il-paradiso-balneare-del-brasile\" target=\"_blank\" rel=\"noreferrer noopener\">buggy<\/a>.<\/p>\n\n<h3 class=\"wp-block-heading\"><strong>Vita notturna e divertimento<\/strong><\/h3>\n\n<p class=\"wp-block-paragraph\">Anche se Jo\u00e3o Fernandes \u00e8 relativamente tranquillo, non \u00e8 privo di intrattenimento. Alcuni bar e club sulla spiaggia offrono musica dal vivo, soprattutto durante la stagione turistica, permettendo ai visitatori di ballare tutta la notte.<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>Suggerimenti per i visitatori<\/strong><\/h2>\n\n<ol class=\"wp-block-list\">\n<li><strong>Periodi di punta:<\/strong> Il quartiere pu\u00f2 essere affollato, soprattutto durante le stagioni turistiche di punta. Se siete alla ricerca di un&#8217;esperienza pi\u00f9 serena, prendete in considerazione l&#8217;idea di visitarla durante i mesi non di punta.<\/li>\n\n\n\n<li><strong>Sicurezza:<\/strong> Sebbene Jo\u00e3o Fernandes sia generalmente sicuro, fate sempre attenzione ai vostri effetti personali, soprattutto in spiaggia.<\/li>\n\n\n\n<li><strong>Sostenibilit\u00e0:<\/strong> contribuire a mantenere il quartiere incontaminato aderendo a pratiche eco-compatibili. Evitate di gettare rifiuti e rispettate la flora e la fauna locali.<\/li>\n<\/ol>\n\n<h2 class=\"wp-block-heading\"><strong>Conclusione<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Jo\u00e3o Fernandes, con il suo fascino accattivante, testimonia la variet\u00e0 dell&#8217;offerta di B\u00fazios. Che si tratti di rilassarsi sulle spiagge, di immergersi in profondit\u00e0 per esplorare le meraviglie marine o di immergersi nella vivace cultura, questo quartiere promette un&#8217;esperienza indimenticabile.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Situato sulla costa nord-orientale della penisola di B\u00fazios, Jo\u00e3o Fernandes \u00e8 un quartiere rinomato per le sue spiagge incontaminate, i suoi resort di lusso e un ambiente che racchiude perfettamente lo spirito di B\u00fazios. Questa zona, che prende il nome dalla sua spiaggia di punta, Praia Jo\u00e3o Fernandes, offre un mix di relax e avventura [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2845,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-3522","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-citta-buzios-brasile"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Distretto Jo\u00e3o Fernandes, B\u00fazios: Un paradiso marino<\/title>\n<meta name=\"description\" content=\"Immergetevi nell&#039;incantevole mondo di Jo\u00e3o Fernandes a B\u00fazios. Dalla sua spiaggia iconica ai resort di lusso, scoprite cosa rende questo quartiere una meta imperdibile della penisola di B\u00fazios.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/buzios-vibe.com\/it\/joao-fernandes-il-quartiere-degli-sport-acquatici-di-buzios\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Distretto Jo\u00e3o Fernandes, B\u00fazios: Un paradiso marino\" \/>\n<meta property=\"og:description\" content=\"Immergetevi nell&#039;incantevole mondo di Jo\u00e3o Fernandes a B\u00fazios. Dalla sua spiaggia iconica ai resort di lusso, scoprite cosa rende questo quartiere una meta imperdibile della penisola di B\u00fazios.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/buzios-vibe.com\/it\/joao-fernandes-il-quartiere-degli-sport-acquatici-di-buzios\" \/>\n<meta property=\"og:site_name\" content=\"Buzios Vibe - all you need to know about Buzios\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-21T15:20:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-15T18:32:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/buzios-vibe.com\/wp-content\/uploads\/2023\/08\/buzios_joao_fernandes-1030x773.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1030\" \/>\n\t<meta property=\"og:image:height\" content=\"773\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Marrai\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marrai\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/buzios-vibe.com\\\/it\\\/joao-fernandes-il-quartiere-degli-sport-acquatici-di-buzios#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/buzios-vibe.com\\\/it\\\/joao-fernandes-il-quartiere-degli-sport-acquatici-di-buzios\"},\"author\":{\"name\":\"Marrai\",\"@id\":\"https:\\\/\\\/buzios-vibe.com\\\/it#\\\/schema\\\/person\\\/20754918872eebfcb85281eb223d4f38\"},\"headline\":\"Jo\u00e3o Fernandes: il quartiere degli sport acquatici di B\u00fazios\",\"datePublished\":\"2023-09-21T15:20:04+00:00\",\"dateModified\":\"2024-11-15T18:32:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/buzios-vibe.com\\\/it\\\/joao-fernandes-il-quartiere-degli-sport-acquatici-di-buzios\"},\"wordCount\":537,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/buzios-vibe.com\\\/it\\\/joao-fernandes-il-quartiere-degli-sport-acquatici-di-buzios#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/buzios-vibe.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/buzios_joao_fernandes.png\",\"articleSection\":[\"La citt\u00e0 B\u00fazios, Brasile\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/buzios-vibe.com\\\/it\\\/joao-fernandes-il-quartiere-degli-sport-acquatici-di-buzios#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/buzios-vibe.com\\\/it\\\/joao-fernandes-il-quartiere-degli-sport-acquatici-di-buzios\",\"url\":\"https:\\\/\\\/buzios-vibe.com\\\/it\\\/joao-fernandes-il-quartiere-degli-sport-acquatici-di-buzios\",\"name\":\"Distretto Jo\u00e3o Fernandes, B\u00fazios: Un paradiso marino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/buzios-vibe.com\\\/it#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/buzios-vibe.com\\\/it\\\/joao-fernandes-il-quartiere-degli-sport-acquatici-di-buzios#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/buzios-vibe.com\\\/it\\\/joao-fernandes-il-quartiere-degli-sport-acquatici-di-buzios#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/buzios-vibe.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/buzios_joao_fernandes.png\",\"datePublished\":\"2023-09-21T15:20:04+00:00\",\"dateModified\":\"2024-11-15T18:32:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/buzios-vibe.com\\\/it#\\\/schema\\\/person\\\/20754918872eebfcb85281eb223d4f38\"},\"description\":\"Immergetevi nell'incantevole mondo di Jo\u00e3o Fernandes a B\u00fazios. Dalla sua spiaggia iconica ai resort di lusso, scoprite cosa rende questo quartiere una meta imperdibile della penisola di B\u00fazios.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/buzios-vibe.com\\\/it\\\/joao-fernandes-il-quartiere-degli-sport-acquatici-di-buzios#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/buzios-vibe.com\\\/it\\\/joao-fernandes-il-quartiere-degli-sport-acquatici-di-buzios\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/buzios-vibe.com\\\/it\\\/joao-fernandes-il-quartiere-degli-sport-acquatici-di-buzios#primaryimage\",\"url\":\"https:\\\/\\\/buzios-vibe.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/buzios_joao_fernandes.png\",\"contentUrl\":\"https:\\\/\\\/buzios-vibe.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/buzios_joao_fernandes.png\",\"width\":3024,\"height\":2268},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/buzios-vibe.com\\\/it\\\/joao-fernandes-il-quartiere-degli-sport-acquatici-di-buzios#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/buzios-vibe.com\\\/it\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jo\u00e3o Fernandes: il quartiere degli sport acquatici di B\u00fazios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/buzios-vibe.com\\\/it#website\",\"url\":\"https:\\\/\\\/buzios-vibe.com\\\/it\",\"name\":\"Buzios Vibe - all you need to know about Buzios\",\"description\":\"Buzios Vibe - all you need to know about Buzios\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/buzios-vibe.com\\\/it?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/buzios-vibe.com\\\/it#\\\/schema\\\/person\\\/20754918872eebfcb85281eb223d4f38\",\"name\":\"Marrai\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0219aa98723cd81d97573db61a2aa109f8f8afe6a33effbffcb4c68f890ad66c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0219aa98723cd81d97573db61a2aa109f8f8afe6a33effbffcb4c68f890ad66c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0219aa98723cd81d97573db61a2aa109f8f8afe6a33effbffcb4c68f890ad66c?s=96&d=mm&r=g\",\"caption\":\"Marrai\"},\"sameAs\":[\"https:\\\/\\\/buzios-vibe.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Distretto Jo\u00e3o Fernandes, B\u00fazios: Un paradiso marino","description":"Immergetevi nell'incantevole mondo di Jo\u00e3o Fernandes a B\u00fazios. Dalla sua spiaggia iconica ai resort di lusso, scoprite cosa rende questo quartiere una meta imperdibile della penisola di B\u00fazios.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/buzios-vibe.com\/it\/joao-fernandes-il-quartiere-degli-sport-acquatici-di-buzios","og_locale":"it_IT","og_type":"article","og_title":"Distretto Jo\u00e3o Fernandes, B\u00fazios: Un paradiso marino","og_description":"Immergetevi nell'incantevole mondo di Jo\u00e3o Fernandes a B\u00fazios. Dalla sua spiaggia iconica ai resort di lusso, scoprite cosa rende questo quartiere una meta imperdibile della penisola di B\u00fazios.","og_url":"https:\/\/buzios-vibe.com\/it\/joao-fernandes-il-quartiere-degli-sport-acquatici-di-buzios","og_site_name":"Buzios Vibe - all you need to know about Buzios","article_published_time":"2023-09-21T15:20:04+00:00","article_modified_time":"2024-11-15T18:32:31+00:00","og_image":[{"width":1030,"height":773,"url":"https:\/\/buzios-vibe.com\/wp-content\/uploads\/2023\/08\/buzios_joao_fernandes-1030x773.png","type":"image\/png"}],"author":"Marrai","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Marrai","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/buzios-vibe.com\/it\/joao-fernandes-il-quartiere-degli-sport-acquatici-di-buzios#article","isPartOf":{"@id":"https:\/\/buzios-vibe.com\/it\/joao-fernandes-il-quartiere-degli-sport-acquatici-di-buzios"},"author":{"name":"Marrai","@id":"https:\/\/buzios-vibe.com\/it#\/schema\/person\/20754918872eebfcb85281eb223d4f38"},"headline":"Jo\u00e3o Fernandes: il quartiere degli sport acquatici di B\u00fazios","datePublished":"2023-09-21T15:20:04+00:00","dateModified":"2024-11-15T18:32:31+00:00","mainEntityOfPage":{"@id":"https:\/\/buzios-vibe.com\/it\/joao-fernandes-il-quartiere-degli-sport-acquatici-di-buzios"},"wordCount":537,"commentCount":0,"image":{"@id":"https:\/\/buzios-vibe.com\/it\/joao-fernandes-il-quartiere-degli-sport-acquatici-di-buzios#primaryimage"},"thumbnailUrl":"https:\/\/buzios-vibe.com\/wp-content\/uploads\/2023\/08\/buzios_joao_fernandes.png","articleSection":["La citt\u00e0 B\u00fazios, Brasile"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/buzios-vibe.com\/it\/joao-fernandes-il-quartiere-degli-sport-acquatici-di-buzios#respond"]}]},{"@type":"WebPage","@id":"https:\/\/buzios-vibe.com\/it\/joao-fernandes-il-quartiere-degli-sport-acquatici-di-buzios","url":"https:\/\/buzios-vibe.com\/it\/joao-fernandes-il-quartiere-degli-sport-acquatici-di-buzios","name":"Distretto Jo\u00e3o Fernandes, B\u00fazios: Un paradiso marino","isPartOf":{"@id":"https:\/\/buzios-vibe.com\/it#website"},"primaryImageOfPage":{"@id":"https:\/\/buzios-vibe.com\/it\/joao-fernandes-il-quartiere-degli-sport-acquatici-di-buzios#primaryimage"},"image":{"@id":"https:\/\/buzios-vibe.com\/it\/joao-fernandes-il-quartiere-degli-sport-acquatici-di-buzios#primaryimage"},"thumbnailUrl":"https:\/\/buzios-vibe.com\/wp-content\/uploads\/2023\/08\/buzios_joao_fernandes.png","datePublished":"2023-09-21T15:20:04+00:00","dateModified":"2024-11-15T18:32:31+00:00","author":{"@id":"https:\/\/buzios-vibe.com\/it#\/schema\/person\/20754918872eebfcb85281eb223d4f38"},"description":"Immergetevi nell'incantevole mondo di Jo\u00e3o Fernandes a B\u00fazios. Dalla sua spiaggia iconica ai resort di lusso, scoprite cosa rende questo quartiere una meta imperdibile della penisola di B\u00fazios.","breadcrumb":{"@id":"https:\/\/buzios-vibe.com\/it\/joao-fernandes-il-quartiere-degli-sport-acquatici-di-buzios#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/buzios-vibe.com\/it\/joao-fernandes-il-quartiere-degli-sport-acquatici-di-buzios"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/buzios-vibe.com\/it\/joao-fernandes-il-quartiere-degli-sport-acquatici-di-buzios#primaryimage","url":"https:\/\/buzios-vibe.com\/wp-content\/uploads\/2023\/08\/buzios_joao_fernandes.png","contentUrl":"https:\/\/buzios-vibe.com\/wp-content\/uploads\/2023\/08\/buzios_joao_fernandes.png","width":3024,"height":2268},{"@type":"BreadcrumbList","@id":"https:\/\/buzios-vibe.com\/it\/joao-fernandes-il-quartiere-degli-sport-acquatici-di-buzios#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/buzios-vibe.com\/it"},{"@type":"ListItem","position":2,"name":"Jo\u00e3o Fernandes: il quartiere degli sport acquatici di B\u00fazios"}]},{"@type":"WebSite","@id":"https:\/\/buzios-vibe.com\/it#website","url":"https:\/\/buzios-vibe.com\/it","name":"Buzios Vibe - all you need to know about Buzios","description":"Buzios Vibe - all you need to know about Buzios","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/buzios-vibe.com\/it?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/buzios-vibe.com\/it#\/schema\/person\/20754918872eebfcb85281eb223d4f38","name":"Marrai","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/0219aa98723cd81d97573db61a2aa109f8f8afe6a33effbffcb4c68f890ad66c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0219aa98723cd81d97573db61a2aa109f8f8afe6a33effbffcb4c68f890ad66c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0219aa98723cd81d97573db61a2aa109f8f8afe6a33effbffcb4c68f890ad66c?s=96&d=mm&r=g","caption":"Marrai"},"sameAs":["https:\/\/buzios-vibe.com"]}]}},"_links":{"self":[{"href":"https:\/\/buzios-vibe.com\/it\/wp-json\/wp\/v2\/posts\/3522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/buzios-vibe.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/buzios-vibe.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/buzios-vibe.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/buzios-vibe.com\/it\/wp-json\/wp\/v2\/comments?post=3522"}],"version-history":[{"count":1,"href":"https:\/\/buzios-vibe.com\/it\/wp-json\/wp\/v2\/posts\/3522\/revisions"}],"predecessor-version":[{"id":3525,"href":"https:\/\/buzios-vibe.com\/it\/wp-json\/wp\/v2\/posts\/3522\/revisions\/3525"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/buzios-vibe.com\/it\/wp-json\/wp\/v2\/media\/2845"}],"wp:attachment":[{"href":"https:\/\/buzios-vibe.com\/it\/wp-json\/wp\/v2\/media?parent=3522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/buzios-vibe.com\/it\/wp-json\/wp\/v2\/categories?post=3522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/buzios-vibe.com\/it\/wp-json\/wp\/v2\/tags?post=3522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}