{"id":3228,"date":"2023-10-03T12:35:27","date_gmt":"2023-10-03T15:35:27","guid":{"rendered":"https:\/\/buzios-vibe.com\/golf-en-buzios-club-de-golf-de-buzios-en-arete"},"modified":"2024-11-15T15:15:39","modified_gmt":"2024-11-15T18:15:39","slug":"golf-en-buzios-club-de-golf-de-buzios-en-arete","status":"publish","type":"post","link":"https:\/\/buzios-vibe.com\/es\/golf-en-buzios-club-de-golf-de-buzios-en-arete","title":{"rendered":"Golf en B\u00fazios: Club de Golf de B\u00fazios en Aret\u00ea"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El Club de Golf de B\u00fazios, junto con el renombrado Golfe Clube Aret\u00ea B\u00fazios, ofrece una experiencia de golf de primera clase en el coraz\u00f3n de esta ciudad tur\u00edstica. Dise\u00f1ado por los arquitectos de golf de talla mundial Pete y Perry Dye, el campo de Aret\u00ea B\u00fazios est\u00e1 reconocido como uno de los mejores de Am\u00e9rica Latina. Aprovechando al m\u00e1ximo la belleza natural de la ciudad, el trazado del campo acent\u00faa los accidentes geogr\u00e1ficos y la topograf\u00eda de la regi\u00f3n. Los golfistas pueden esperar un juego desafiante en sus 7.000 yardas, con 18 greens, 14 lagos artificiales y bancos de arena.<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>Caracter\u00edsticas del campo<\/strong> de golf<\/h2>\n\n<ul class=\"wp-block-list\">\n<li><strong>18 hoyos:<\/strong> Ofrece hoyos largos y cortos para poner a prueba sus habilidades.<\/li>\n\n\n\n<li><strong>Peligros de agua:<\/strong> El campo incluye una variedad de obst\u00e1culos de agua, por lo que el juego estrat\u00e9gico es esencial.<\/li>\n\n\n\n<li><strong>Mantenimiento impecable:<\/strong> Verdes, b\u00fankers y calles bien cuidados.<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\"><strong>Tee off con vistas<\/strong> <\/h2>\n\n<p class=\"wp-block-paragraph\">Uno de los puntos fuertes del golf en B\u00fazios es la vista. A medida que avanza por el recorrido, disfrutar\u00e1 de vistas panor\u00e1micas del exuberante paisaje circundante y del mar azul. Esta mezcla de belleza natural y deporte constituye una experiencia golf\u00edstica inolvidable.<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>Formaci\u00f3n e instalaciones<\/strong><\/h2>\n\n<ul class=\"wp-block-list\">\n<li><strong>Campo de pr\u00e1cticas:<\/strong> Perfecto para practicar sus golpes antes de salir al campo.<\/li>\n\n\n\n<li><strong>Profesional del golf:<\/strong> Las clases est\u00e1n disponibles tanto para principiantes como para aquellos que buscan mejorar su juego.<\/li>\n\n\n\n<li><strong>Casa Club:<\/strong> La Casa Club Aret\u00ea B\u00fazios sirve de coraz\u00f3n a los golfistas. Dispone de un amplio sal\u00f3n con TV conectada a las principales cadenas mundiales de deportes de golf, un almac\u00e9n bien organizado, aparcamiento para carritos de golf, una estaci\u00f3n de limpieza y pulido de palos de golf, y un bar y restaurante con un men\u00fa elaborado exclusivamente para los entusiastas del golf.<\/li>\n\n\n\n<li><strong>Minigolf:<\/strong> Situado junto al campo de golf principal y justo detr\u00e1s de las pistas de tenis de playa, un espacio dedicado al minigolf da la bienvenida tanto a los nuevos aprendices como a los que buscan diversi\u00f3n sin prisas.<\/li>\n\n\n\n<li><strong>Alquiler de<\/strong> carritos de golf<strong>:<\/strong> El club dispone de un garaje para aparcar, cargar bater\u00edas y alquilar carritos de golf tanto para socios como para visitantes.<\/li>\n\n\n\n<li><strong>Green Fee:<\/strong> Los golfistas no socios que deseen conocer el campo de Aret\u00ea B\u00fazios pueden beneficiarse del Green Fee, que garantiza un d\u00eda espl\u00e9ndido en uno de los mejores campos de golf de Am\u00e9rica Latina.<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\"><strong>Accesibilidad y comodidad<\/strong><\/h2>\n\n<ul class=\"wp-block-list\">\n<li><strong>Localizaci\u00f3n:<\/strong> El club de golf suele estar a 20-30 minutos en coche de la mayor\u00eda de los complejos tur\u00edsticos y hoteles de B\u00fazios. Si busca un hotel cercano le recomendamos que se aloje en el <a href=\"https:\/\/www.hotels.com\/affiliate\/F9coEV1\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Hotel Aret\u00ea<\/a>, que tiene 4 Estrellas y forma parte del mismo complejo. O lea nuestra sugerencia de <a href=\"https:\/\/buzios-vibe.com\/es\/5-hoteles-en-la-playa-de-buzios-para-todos-los-bolsillos\" target=\"_blank\" rel=\"noreferrer noopener\">hoteles en primera l\u00ednea de<\/a> playa.<\/li>\n\n\n\n<li><strong>Alquiler de equipo:<\/strong> Si no le apetece traer su propio equipo, hay opciones de alquiler disponibles.<\/li>\n\n\n\n<li><strong>Reservas:<\/strong> Aunque a menudo se aceptan visitas sin cita previa, es aconsejable reservar con antelaci\u00f3n, sobre todo en temporada alta.<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\"><strong>Eventos y torneos<\/strong> <\/h2>\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s de sus inigualables instalaciones, el Golfe Clube Aret\u00ea B\u00fazios se distingue por sus eventos regulares dirigidos tanto a aficionados como a profesionales. Estos torneos ofrecen a los golfistas la oportunidad no s\u00f3lo de desafiarse a s\u00ed mismos, sino tambi\u00e9n de relacionarse con otros entusiastas, fomentando as\u00ed una vibrante comunidad de golf. El club tambi\u00e9n imparte cursillos especializados, dise\u00f1ados para introducir a adultos y ni\u00f1os por igual en los matices del juego, garantizando que el legado de este deporte contin\u00fae con las generaciones m\u00e1s j\u00f3venes.<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>Horario de atenci\u00f3n al p\u00fablico<\/strong> <\/h2>\n\n<p class=\"wp-block-paragraph\">Para aquellos que planean una visita, es esencial tener en cuenta que el Golfe Clube Aret\u00ea B\u00fazios opera de martes a domingo entre las 07:00 AM y las 17:00 PM, asegurando tiempo suficiente para que los entusiastas se entreguen a su pasi\u00f3n.<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>Fuera del campo: Explorando B\u00fazios<\/strong> <\/h2>\n\n<p class=\"wp-block-paragraph\">Lo que distingue a B\u00fazios como destino de golf es lo que se puede hacer fuera del campo. Ya sea explorando sus m\u00e1s de 20 playas, degustando la <a href=\"https:\/\/buzios-vibe.com\/es\/un-viaje-culinario-por-buzios-descubra-los-sabores-de-la-joya-costera-de-brasil\" target=\"_blank\" rel=\"noreferrer noopener\">gastronom\u00eda local<\/a> o disfrutando de su animada vida nocturna, B\u00fazios ofrece una experiencia vacacional completa.<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>Conclusi\u00f3n<\/strong> <\/h2>\n\n<p class=\"wp-block-paragraph\">El golf en B\u00fazios ofrece una mezcla \u00fanica de deporte desafiante y belleza natural impresionante. Con sus instalaciones de categor\u00eda mundial y la variada gama de actividades disponibles fuera del campo, B\u00fazios presenta un argumento convincente para sus pr\u00f3ximas vacaciones de golf. Tanto si es un golfista experimentado como si es nuevo en este deporte, los campos ofrecen una experiencia atractiva y desafiante que no olvidar\u00e1 en mucho tiempo. As\u00ed que empaque sus palos y prep\u00e1rese para una experiencia golf\u00edstica inolvidable en el coraz\u00f3n del para\u00edso costero de Brasil.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Club de Golf de B\u00fazios, junto con el renombrado Golfe Clube Aret\u00ea B\u00fazios, ofrece una experiencia de golf de primera clase en el coraz\u00f3n de esta ciudad tur\u00edstica. Dise\u00f1ado por los arquitectos de golf de talla mundial Pete y Perry Dye, el campo de Aret\u00ea B\u00fazios est\u00e1 reconocido como uno de los mejores de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2657,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[77],"tags":[],"class_list":["post-3228","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actividades-en-buzios-brasil"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Golf en B\u00fazios: Campo de Golf de 18 hoyos en Aret\u00ea | Buzios Vibe<\/title>\n<meta name=\"description\" content=\"Explore el Club de Golf B\u00fazios 18 hoyos con lagos, dise\u00f1ado por Pete y Perry Dye, y descubra por qu\u00e9 est\u00e1 considerado uno de los mejores de Latinoam\u00e9rica. Sum\u00e9rjase en unas instalaciones de categor\u00eda mundial, unas vistas impresionantes y una rica cultura del golf con el pintoresco tel\u00f3n de fondo de Brasil. \u00a1Sus pr\u00f3ximas vacaciones de golf le esperan en B\u00fazios!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/buzios-vibe.com\/es\/golf-en-buzios-club-de-golf-de-buzios-en-arete\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Golf en B\u00fazios: Campo de Golf de 18 hoyos en Aret\u00ea | Buzios Vibe\" \/>\n<meta property=\"og:description\" content=\"Explore el Club de Golf B\u00fazios 18 hoyos con lagos, dise\u00f1ado por Pete y Perry Dye, y descubra por qu\u00e9 est\u00e1 considerado uno de los mejores de Latinoam\u00e9rica. Sum\u00e9rjase en unas instalaciones de categor\u00eda mundial, unas vistas impresionantes y una rica cultura del golf con el pintoresco tel\u00f3n de fondo de Brasil. \u00a1Sus pr\u00f3ximas vacaciones de golf le esperan en B\u00fazios!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/buzios-vibe.com\/es\/golf-en-buzios-club-de-golf-de-buzios-en-arete\" \/>\n<meta property=\"og:site_name\" content=\"Buzios Vibe - all you need to know about Buzios\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-03T15:35:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-15T18:15:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/buzios-vibe.com\/wp-content\/uploads\/2023\/08\/golfing_buzios_arete_travel_blog-1030x772.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1030\" \/>\n\t<meta property=\"og:image:height\" content=\"772\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Marrai\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marrai\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/buzios-vibe.com\\\/es\\\/golf-en-buzios-club-de-golf-de-buzios-en-arete#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/buzios-vibe.com\\\/es\\\/golf-en-buzios-club-de-golf-de-buzios-en-arete\"},\"author\":{\"name\":\"Marrai\",\"@id\":\"https:\\\/\\\/buzios-vibe.com\\\/es#\\\/schema\\\/person\\\/20754918872eebfcb85281eb223d4f38\"},\"headline\":\"Golf en B\u00fazios: Club de Golf de B\u00fazios en Aret\u00ea\",\"datePublished\":\"2023-10-03T15:35:27+00:00\",\"dateModified\":\"2024-11-15T18:15:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/buzios-vibe.com\\\/es\\\/golf-en-buzios-club-de-golf-de-buzios-en-arete\"},\"wordCount\":834,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/buzios-vibe.com\\\/es\\\/golf-en-buzios-club-de-golf-de-buzios-en-arete#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/buzios-vibe.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/golfing_buzios_arete_travel_blog.png\",\"articleSection\":[\"Actividades en B\u00fazios, Brasil\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/buzios-vibe.com\\\/es\\\/golf-en-buzios-club-de-golf-de-buzios-en-arete#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/buzios-vibe.com\\\/es\\\/golf-en-buzios-club-de-golf-de-buzios-en-arete\",\"url\":\"https:\\\/\\\/buzios-vibe.com\\\/es\\\/golf-en-buzios-club-de-golf-de-buzios-en-arete\",\"name\":\"Golf en B\u00fazios: Campo de Golf de 18 hoyos en Aret\u00ea | Buzios Vibe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/buzios-vibe.com\\\/es#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/buzios-vibe.com\\\/es\\\/golf-en-buzios-club-de-golf-de-buzios-en-arete#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/buzios-vibe.com\\\/es\\\/golf-en-buzios-club-de-golf-de-buzios-en-arete#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/buzios-vibe.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/golfing_buzios_arete_travel_blog.png\",\"datePublished\":\"2023-10-03T15:35:27+00:00\",\"dateModified\":\"2024-11-15T18:15:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/buzios-vibe.com\\\/es#\\\/schema\\\/person\\\/20754918872eebfcb85281eb223d4f38\"},\"description\":\"Explore el Club de Golf B\u00fazios 18 hoyos con lagos, dise\u00f1ado por Pete y Perry Dye, y descubra por qu\u00e9 est\u00e1 considerado uno de los mejores de Latinoam\u00e9rica. Sum\u00e9rjase en unas instalaciones de categor\u00eda mundial, unas vistas impresionantes y una rica cultura del golf con el pintoresco tel\u00f3n de fondo de Brasil. \u00a1Sus pr\u00f3ximas vacaciones de golf le esperan en B\u00fazios!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/buzios-vibe.com\\\/es\\\/golf-en-buzios-club-de-golf-de-buzios-en-arete#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/buzios-vibe.com\\\/es\\\/golf-en-buzios-club-de-golf-de-buzios-en-arete\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/buzios-vibe.com\\\/es\\\/golf-en-buzios-club-de-golf-de-buzios-en-arete#primaryimage\",\"url\":\"https:\\\/\\\/buzios-vibe.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/golfing_buzios_arete_travel_blog.png\",\"contentUrl\":\"https:\\\/\\\/buzios-vibe.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/golfing_buzios_arete_travel_blog.png\",\"width\":3022,\"height\":2266},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/buzios-vibe.com\\\/es\\\/golf-en-buzios-club-de-golf-de-buzios-en-arete#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/buzios-vibe.com\\\/es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Golf en B\u00fazios: Club de Golf de B\u00fazios en Aret\u00ea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/buzios-vibe.com\\\/es#website\",\"url\":\"https:\\\/\\\/buzios-vibe.com\\\/es\",\"name\":\"Buzios Vibe - all you need to know about Buzios\",\"description\":\"Buzios Vibe - all you need to know about Buzios\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/buzios-vibe.com\\\/es?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/buzios-vibe.com\\\/es#\\\/schema\\\/person\\\/20754918872eebfcb85281eb223d4f38\",\"name\":\"Marrai\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0219aa98723cd81d97573db61a2aa109f8f8afe6a33effbffcb4c68f890ad66c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0219aa98723cd81d97573db61a2aa109f8f8afe6a33effbffcb4c68f890ad66c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0219aa98723cd81d97573db61a2aa109f8f8afe6a33effbffcb4c68f890ad66c?s=96&d=mm&r=g\",\"caption\":\"Marrai\"},\"sameAs\":[\"https:\\\/\\\/buzios-vibe.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Golf en B\u00fazios: Campo de Golf de 18 hoyos en Aret\u00ea | Buzios Vibe","description":"Explore el Club de Golf B\u00fazios 18 hoyos con lagos, dise\u00f1ado por Pete y Perry Dye, y descubra por qu\u00e9 est\u00e1 considerado uno de los mejores de Latinoam\u00e9rica. Sum\u00e9rjase en unas instalaciones de categor\u00eda mundial, unas vistas impresionantes y una rica cultura del golf con el pintoresco tel\u00f3n de fondo de Brasil. \u00a1Sus pr\u00f3ximas vacaciones de golf le esperan en B\u00fazios!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/buzios-vibe.com\/es\/golf-en-buzios-club-de-golf-de-buzios-en-arete","og_locale":"es_ES","og_type":"article","og_title":"Golf en B\u00fazios: Campo de Golf de 18 hoyos en Aret\u00ea | Buzios Vibe","og_description":"Explore el Club de Golf B\u00fazios 18 hoyos con lagos, dise\u00f1ado por Pete y Perry Dye, y descubra por qu\u00e9 est\u00e1 considerado uno de los mejores de Latinoam\u00e9rica. Sum\u00e9rjase en unas instalaciones de categor\u00eda mundial, unas vistas impresionantes y una rica cultura del golf con el pintoresco tel\u00f3n de fondo de Brasil. \u00a1Sus pr\u00f3ximas vacaciones de golf le esperan en B\u00fazios!","og_url":"https:\/\/buzios-vibe.com\/es\/golf-en-buzios-club-de-golf-de-buzios-en-arete","og_site_name":"Buzios Vibe - all you need to know about Buzios","article_published_time":"2023-10-03T15:35:27+00:00","article_modified_time":"2024-11-15T18:15:39+00:00","og_image":[{"width":1030,"height":772,"url":"https:\/\/buzios-vibe.com\/wp-content\/uploads\/2023\/08\/golfing_buzios_arete_travel_blog-1030x772.png","type":"image\/png"}],"author":"Marrai","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marrai","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/buzios-vibe.com\/es\/golf-en-buzios-club-de-golf-de-buzios-en-arete#article","isPartOf":{"@id":"https:\/\/buzios-vibe.com\/es\/golf-en-buzios-club-de-golf-de-buzios-en-arete"},"author":{"name":"Marrai","@id":"https:\/\/buzios-vibe.com\/es#\/schema\/person\/20754918872eebfcb85281eb223d4f38"},"headline":"Golf en B\u00fazios: Club de Golf de B\u00fazios en Aret\u00ea","datePublished":"2023-10-03T15:35:27+00:00","dateModified":"2024-11-15T18:15:39+00:00","mainEntityOfPage":{"@id":"https:\/\/buzios-vibe.com\/es\/golf-en-buzios-club-de-golf-de-buzios-en-arete"},"wordCount":834,"commentCount":0,"image":{"@id":"https:\/\/buzios-vibe.com\/es\/golf-en-buzios-club-de-golf-de-buzios-en-arete#primaryimage"},"thumbnailUrl":"https:\/\/buzios-vibe.com\/wp-content\/uploads\/2023\/08\/golfing_buzios_arete_travel_blog.png","articleSection":["Actividades en B\u00fazios, Brasil"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/buzios-vibe.com\/es\/golf-en-buzios-club-de-golf-de-buzios-en-arete#respond"]}]},{"@type":"WebPage","@id":"https:\/\/buzios-vibe.com\/es\/golf-en-buzios-club-de-golf-de-buzios-en-arete","url":"https:\/\/buzios-vibe.com\/es\/golf-en-buzios-club-de-golf-de-buzios-en-arete","name":"Golf en B\u00fazios: Campo de Golf de 18 hoyos en Aret\u00ea | Buzios Vibe","isPartOf":{"@id":"https:\/\/buzios-vibe.com\/es#website"},"primaryImageOfPage":{"@id":"https:\/\/buzios-vibe.com\/es\/golf-en-buzios-club-de-golf-de-buzios-en-arete#primaryimage"},"image":{"@id":"https:\/\/buzios-vibe.com\/es\/golf-en-buzios-club-de-golf-de-buzios-en-arete#primaryimage"},"thumbnailUrl":"https:\/\/buzios-vibe.com\/wp-content\/uploads\/2023\/08\/golfing_buzios_arete_travel_blog.png","datePublished":"2023-10-03T15:35:27+00:00","dateModified":"2024-11-15T18:15:39+00:00","author":{"@id":"https:\/\/buzios-vibe.com\/es#\/schema\/person\/20754918872eebfcb85281eb223d4f38"},"description":"Explore el Club de Golf B\u00fazios 18 hoyos con lagos, dise\u00f1ado por Pete y Perry Dye, y descubra por qu\u00e9 est\u00e1 considerado uno de los mejores de Latinoam\u00e9rica. Sum\u00e9rjase en unas instalaciones de categor\u00eda mundial, unas vistas impresionantes y una rica cultura del golf con el pintoresco tel\u00f3n de fondo de Brasil. \u00a1Sus pr\u00f3ximas vacaciones de golf le esperan en B\u00fazios!","breadcrumb":{"@id":"https:\/\/buzios-vibe.com\/es\/golf-en-buzios-club-de-golf-de-buzios-en-arete#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/buzios-vibe.com\/es\/golf-en-buzios-club-de-golf-de-buzios-en-arete"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/buzios-vibe.com\/es\/golf-en-buzios-club-de-golf-de-buzios-en-arete#primaryimage","url":"https:\/\/buzios-vibe.com\/wp-content\/uploads\/2023\/08\/golfing_buzios_arete_travel_blog.png","contentUrl":"https:\/\/buzios-vibe.com\/wp-content\/uploads\/2023\/08\/golfing_buzios_arete_travel_blog.png","width":3022,"height":2266},{"@type":"BreadcrumbList","@id":"https:\/\/buzios-vibe.com\/es\/golf-en-buzios-club-de-golf-de-buzios-en-arete#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/buzios-vibe.com\/es"},{"@type":"ListItem","position":2,"name":"Golf en B\u00fazios: Club de Golf de B\u00fazios en Aret\u00ea"}]},{"@type":"WebSite","@id":"https:\/\/buzios-vibe.com\/es#website","url":"https:\/\/buzios-vibe.com\/es","name":"Buzios Vibe - all you need to know about Buzios","description":"Buzios Vibe - all you need to know about Buzios","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/buzios-vibe.com\/es?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/buzios-vibe.com\/es#\/schema\/person\/20754918872eebfcb85281eb223d4f38","name":"Marrai","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0219aa98723cd81d97573db61a2aa109f8f8afe6a33effbffcb4c68f890ad66c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0219aa98723cd81d97573db61a2aa109f8f8afe6a33effbffcb4c68f890ad66c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0219aa98723cd81d97573db61a2aa109f8f8afe6a33effbffcb4c68f890ad66c?s=96&d=mm&r=g","caption":"Marrai"},"sameAs":["https:\/\/buzios-vibe.com"]}]}},"_links":{"self":[{"href":"https:\/\/buzios-vibe.com\/es\/wp-json\/wp\/v2\/posts\/3228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/buzios-vibe.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/buzios-vibe.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/buzios-vibe.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/buzios-vibe.com\/es\/wp-json\/wp\/v2\/comments?post=3228"}],"version-history":[{"count":4,"href":"https:\/\/buzios-vibe.com\/es\/wp-json\/wp\/v2\/posts\/3228\/revisions"}],"predecessor-version":[{"id":3851,"href":"https:\/\/buzios-vibe.com\/es\/wp-json\/wp\/v2\/posts\/3228\/revisions\/3851"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/buzios-vibe.com\/es\/wp-json\/wp\/v2\/media\/2657"}],"wp:attachment":[{"href":"https:\/\/buzios-vibe.com\/es\/wp-json\/wp\/v2\/media?parent=3228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/buzios-vibe.com\/es\/wp-json\/wp\/v2\/categories?post=3228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/buzios-vibe.com\/es\/wp-json\/wp\/v2\/tags?post=3228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}